{"id":163184,"date":"2026-05-08T11:59:49","date_gmt":"2026-05-08T11:59:49","guid":{"rendered":"https:\/\/hilcoindustrial.com\/lot\/sfln-008474"},"modified":"2026-05-08T11:59:49","modified_gmt":"2026-05-08T11:59:49","slug":"siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai","status":"publish","type":"lots","link":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai","title":{"rendered":"SFLN-008474"},"parent":0,"template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"lot-tags":[],"class_list":["post-163184","lots","type-lots","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SFLN-008474 - Hilco Industrial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SFLN-008474 - Hilco Industrial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai\" \/>\n<meta property=\"og:site_name\" content=\"Hilco Industrial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\\\/lot\\\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai\",\"url\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\\\/lot\\\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai\",\"name\":\"SFLN-008474 - Hilco Industrial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans#website\"},\"datePublished\":\"2026-05-08T11:59:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\\\/lot\\\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\\\/lot\\\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\\\/lot\\\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SFLN-008474\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans#website\",\"url\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans\",\"name\":\"Hilco Industrial\",\"description\":\"Hilco Industrial sells Machinery &amp; Equipment from closed-down industrial production companies worldwide, large factories, who have maintained their machinery well.The Machinery &amp; Equipment is always sold directly from the factory.\",\"alternateName\":\"Hilco Auctions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hilcoindustrial.com\\\/zh-hans?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SFLN-008474 - Hilco Industrial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai","og_locale":"zh_CN","og_type":"article","og_title":"SFLN-008474 - Hilco Industrial","og_url":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai","og_site_name":"Hilco Industrial","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai","url":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai","name":"SFLN-008474 - Hilco Industrial","isPartOf":{"@id":"https:\/\/hilcoindustrial.com\/zh-hans#website"},"datePublished":"2026-05-08T11:59:49+00:00","breadcrumb":{"@id":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hilcoindustrial.com\/zh-hans\/lot\/siemens-8da10-gas-insulated-switchgear-36-kv-630-a-a03rk00000n8cgyiai#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hilcoindustrial.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"SFLN-008474"}]},{"@type":"WebSite","@id":"https:\/\/hilcoindustrial.com\/zh-hans#website","url":"https:\/\/hilcoindustrial.com\/zh-hans","name":"Hilco Industrial","description":"Hilco Industrial sells Machinery &amp; Equipment from closed-down industrial production companies worldwide, large factories, who have maintained their machinery well.The Machinery &amp; Equipment is always sold directly from the factory.","alternateName":"Hilco Auctions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hilcoindustrial.com\/zh-hans?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/hilcoindustrial.com\/zh-hans\/wp-json\/wp\/v2\/lots\/163184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hilcoindustrial.com\/zh-hans\/wp-json\/wp\/v2\/lots"}],"about":[{"href":"https:\/\/hilcoindustrial.com\/zh-hans\/wp-json\/wp\/v2\/types\/lots"}],"wp:attachment":[{"href":"https:\/\/hilcoindustrial.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=163184"}],"wp:term":[{"taxonomy":"lot-tags","embeddable":true,"href":"https:\/\/hilcoindustrial.com\/zh-hans\/wp-json\/wp\/v2\/lot-tags?post=163184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}